{"id":30636,"date":"2025-08-31T10:15:26","date_gmt":"2025-08-31T08:15:26","guid":{"rendered":"https:\/\/glaciersalive.ch\/?page_id=30636"},"modified":"2026-02-27T22:12:48","modified_gmt":"2026-02-27T21:12:48","slug":"projekte-2","status":"publish","type":"page","link":"https:\/\/glaciersalive.ch\/en\/projekte-2\/","title":{"rendered":"Projects"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; disabled_on=&#8220;on|on|off&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_menu menu_id=&#8220;14&#8243; fullwidth_menu=&#8220;off&#8220; logo=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/IMG_1429.jpg&#8220; logo_width=&#8220;32%&#8220; show_search_icon=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; menu_font_size=&#8220;16px&#8220; text_orientation=&#8220;right&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_menu][et_pb_fullwidth_menu menu_style=&#8220;centered&#8220; fullwidth_menu=&#8220;off&#8220; active_link_color=&#8220;#FFFFFF&#8220; logo_height=&#8220;104px&#8220; logo_max_height=&#8220;78px&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; menu_text_color=&#8220;#FFFFFF&#8220; menu_font_size=&#8220;20px&#8220; background_color=&#8220;#072130&#8243; custom_padding=&#8220;1px|||||&#8220; child_filter_hue_rotate=&#8220;359deg&#8220; child_filter_brightness=&#8220;200%&#8220; child_filter_contrast=&#8220;0%&#8220; border_color_all_image=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_menu][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; fullwidth=&#8220;on&#8220; disabled_on=&#8220;off|off|on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_fullwidth_menu menu_id=&#8220;14&#8243; fullwidth_menu=&#8220;off&#8220; logo=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/IMG_1429.jpg&#8220; logo_width=&#8220;76%&#8220; show_search_icon=&#8220;on&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; menu_font_size=&#8220;16px&#8220; text_orientation=&#8220;right&#8220; custom_padding=&#8220;||0px|||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_menu][et_pb_fullwidth_menu menu_style=&#8220;centered&#8220; fullwidth_menu=&#8220;off&#8220; active_link_color=&#8220;#FFFFFF&#8220; logo_height=&#8220;104px&#8220; logo_max_height=&#8220;78px&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; menu_text_color=&#8220;#FFFFFF&#8220; menu_font_size=&#8220;20px&#8220; background_color=&#8220;#072130&#8243; custom_padding=&#8220;1px|||||&#8220; child_filter_hue_rotate=&#8220;359deg&#8220; child_filter_brightness=&#8220;200%&#8220; child_filter_contrast=&#8220;0%&#8220; border_color_all_image=&#8220;#FFFFFF&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_fullwidth_menu][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;on|off|off&#8220; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;f08e7613-a180-4797-9c4f-8fef2b5afe95&#8243; background_color_gradient_stops=&#8220;gcid-d119accd-44d7-4f2f-b9d7-599c8463324b 0%|rgba(255,255,255,0) 100%|rgba(7,33,48,0.6) 100%|#072130 100%&#8220; background_image=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/11\/Fleece-scaled.jpg&#8220; background_enable_image=&#8220;on&#8220; locked=&#8220;off&#8220; collapsed=&#8220;on&#8220; global_colors_info=&#8220;{%22gcid-1f1bf5fb-a99d-4acc-8d9e-ddac074c158c%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-4c79ba3d-a281-4fb6-9b14-02f9a4c793f2%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-688c464a-d6f2-4296-b592-395352c71c79%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-d119accd-44d7-4f2f-b9d7-599c8463324b%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93}&#8220;][et_pb_row _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; width=&#8220;84.4%&#8220; custom_padding=&#8220;||3px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_heading title=&#8220;Unsere Projekte&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;9bab56d2-91ba-4ba3-b0ff-49ada2eb4275&#8243; title_text_align=&#8220;center&#8220; title_text_color=&#8220;#FFFFFF&#8220; title_font_size=&#8220;90px&#8220; custom_margin=&#8220;||10px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; disabled_on=&#8220;off|on|on&#8220; admin_label=&#8220;Header&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;f08e7613-a180-4797-9c4f-8fef2b5afe95&#8243; background_color_gradient_stops=&#8220;gcid-d119accd-44d7-4f2f-b9d7-599c8463324b 0%|rgba(255,255,255,0) 100%|rgba(7,33,48,0.6) 100%|#072130 100%&#8220; background_image=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/11\/Fleece-scaled.jpg&#8220; background_enable_image=&#8220;on&#8220; locked=&#8220;off&#8220; collapsed=&#8220;on&#8220; global_colors_info=&#8220;{%22gcid-1f1bf5fb-a99d-4acc-8d9e-ddac074c158c%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-4c79ba3d-a281-4fb6-9b14-02f9a4c793f2%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-688c464a-d6f2-4296-b592-395352c71c79%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93,%22gcid-d119accd-44d7-4f2f-b9d7-599c8463324b%22:%91%22background_color_gradient_stops%22,%22background_color_gradient_stops%22%93}&#8220;][et_pb_row _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; width=&#8220;84.4%&#8220; custom_padding=&#8220;||3px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_heading title=&#8220;Unsere Projekte&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;9bab56d2-91ba-4ba3-b0ff-49ada2eb4275&#8243; title_text_align=&#8220;center&#8220; title_text_color=&#8220;#FFFFFF&#8220; title_font_size=&#8220;90px&#8220; custom_margin=&#8220;||10px||false|false&#8220; title_font_size_phone=&#8220;49px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; specialty=&#8220;on&#8220; admin_label=&#8220;How You Can Help&#8220; _builder_version=&#8220;4.25.1&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;20px||4px|||&#8220; collapsed=&#8220;on&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_blurb title=&#8220;Unsere Projekte &#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x52;||divi||400&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;520394ef-573a-4d2b-b5ad-d2b6a0fe8d30&#8243; header_font=&#8220;Urbanist|&#8211;et_global_heading_font_weight|||||||&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{%22gcid-1f1b4e15-7cc6-4e13-8154-74d77a956460%22:%91%22icon_color%22%93}&#8220;]<\/p>\n<p>GlaciersAlive setzt sich mit innovativen und wissenschaftlich begleiteten Projekten f\u00fcr den Schutz von Gletschern ein. Von Ice Stupas \u00fcber reflektierende Schneedecken bis hin zu neuen Beschneiungstechnologien \u2013 die Projekte tragen dazu bei, Schmelzprozesse zu verlangsamen und Wasser langfristig zu sichern.<\/p>\n<p>[\/et_pb_blurb][et_pb_blurb title=&#8220;GlaciersAlive unterst\u00fctzen&#8220; use_icon=&#8220;on&#8220; font_icon=&#8220;&#x52;||divi||400&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;520394ef-573a-4d2b-b5ad-d2b6a0fe8d30&#8243; header_font=&#8220;Urbanist|&#8211;et_global_heading_font_weight|||||||&#8220; header_font_size_tablet=&#8220;&#8220; header_font_size_phone=&#8220;&#8220; header_font_size_last_edited=&#8220;on|phone&#8220; global_colors_info=&#8220;{%22gcid-1f1b4e15-7cc6-4e13-8154-74d77a956460%22:%91%22icon_color%22%93}&#8220;]<\/p>\n<p>Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer <a href=\"https:\/\/glaciersalive.ch\/spenden-2\/\">Spende<\/a> dabei, die Gletscherwelt lebendig zu bewahren.<\/p>\n<p>[\/et_pb_blurb][\/et_pb_column][et_pb_column type=&#8220;1_2&#8243; specialty_columns=&#8220;2&#8243; _builder_version=&#8220;4.16&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_row_inner _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column_inner saved_specialty_column_type=&#8220;1_2&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][dsm_before_after_image before_src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/11\/20241021_150529.jpg&#8220; after_src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-3-scaled.jpg&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; width=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/dsm_before_after_image][\/et_pb_column_inner][\/et_pb_row_inner][\/et_pb_column][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;Listings&#8220; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;1px||1px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;47a4e8bb-1290-4493-9ff7-76771c89e05e&#8220; custom_padding=&#8220;21px||19px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_heading title=&#8220;\u00dcBERSICHT PROJEKTE&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;ae9dd2a6-6e79-4084-8b63-67ad055d8009&#8243; title_font=&#8220;Urbanist||||||||&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;47a4e8bb-1290-4493-9ff7-76771c89e05e&#8220; custom_padding=&#8220;2px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Schneiseil.jpg&#8220; url=&#8220;https:\/\/glaciersalive.ch\/schneiseil-testanlage-diavolezza\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Schneiseil Testanlage Diavolezza&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Ein bodenunabh\u00e4ngiges Beschneiungssystem f\u00fcr den Gletscherschutz.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/2-2.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/mastercard-projekt\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Mastercard Projekt&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Initiiert von Mastercard setzt die GlaciersAlive Foundation die Kampagne \u00abLasst uns sch\u00fctzen, was wirklich Priceless ist\u00bb zum Schutz Schweizer Gletscher um.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/1-2.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/vlies-abdeckungen\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Vlies Abdeckungen&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Vlies abdeckungen sind eine der einzigen erfolgreich umgesetzten Methoden, um Schnee und Gletscher zu konservieren, indem sie den darunter liegenden Schnee vor dem Schmelzen sch\u00fctzen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;47a4e8bb-1290-4493-9ff7-76771c89e05e&#8220; custom_padding=&#8220;||12px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/11\/12.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/swiss-ice-fiddlers-tango-glaciar\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Swiss Ice Fiddlers &#038; Tango Glaciar&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<article class=\"text-token-text-primary w-full focus:outline-none [--shadow-height:45px] has-data-writing-block:pointer-events-none has-data-writing-block:-mt-(--shadow-height) has-data-writing-block:pt-(--shadow-height) [&amp;:has([data-writing-block])&gt;*]:pointer-events-auto [content-visibility:auto] supports-[content-visibility:auto]:[contain-intrinsic-size:auto_100lvh] scroll-mt-[calc(var(--header-height)+min(200px,max(70px,20svh)))]\" dir=\"auto\" tabindex=\"-1\" data-turn-id=\"request-WEB:57774eb6-f0c9-4f43-a1d2-bb02c7029c56-1\" data-testid=\"conversation-turn-4\" data-scroll-anchor=\"true\" data-turn=\"assistant\">\n<div class=\"text-base my-auto mx-auto pb-10 [--thread-content-margin:--spacing(4)] thread-sm:[--thread-content-margin:--spacing(6)] thread-lg:[--thread-content-margin:--spacing(16)] px-(--thread-content-margin)\">\n<div class=\"[--thread-content-max-width:40rem] thread-lg:[--thread-content-max-width:48rem] mx-auto max-w-(--thread-content-max-width) flex-1 group\/turn-messages focus-visible:outline-hidden relative flex w-full min-w-0 flex-col agent-turn\" tabindex=\"-1\">\n<div class=\"flex max-w-full flex-col grow\">\n<div class=\"min-h-8 text-message relative flex w-full flex-col items-end gap-2 text-start break-words whitespace-normal [.text-message+&amp;]:mt-1\" dir=\"auto\" data-message-author-role=\"assistant\" data-message-id=\"76d0f792-2a56-4437-9406-59f8e903decc\" data-message-model-slug=\"gpt-5\">\n<div class=\"flex w-full flex-col gap-1 empty:hidden first:pt-[1px]\">\n<div class=\"markdown prose dark:prose-invert w-full break-words light markdown-new-styling\">\n<p data-start=\"0\" data-end=\"153\" data-is-last-node=\"\" data-is-only-node=\"\">Die beiden Musikgruppen Tango Glaciar und Swiss Ice Fiddlers haben ein gemeinsames Ziel: Gletscher, Klimaschutz und Musik in Einklang zu bringen.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"z-0 flex min-h-[46px] justify-start\">\u00a0<\/div>\n<\/div>\n<\/div>\n<\/article>\n<div class=\"pointer-events-none h-px w-px\" aria-hidden=\"true\" data-edge=\"true\">\u00a0<\/div>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/4-2.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/ice-stupa-testanlage-diavolezza\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Ice Stupa Testanlage Diavolezza&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Am 11. Februar 2021, wurde die neue Schneiseil- und Ice-Stupa-Testanlage an der Talstation Diavolezza im Oberengadin erstmals in Betrieb genommen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/3-2.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/projekt-ice-stupa\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Ice Stupa Projekt&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mit der \u201cIce Stupa Artifical Ice Reservoir Technology\u201c (AIR) wird ungenutztes Wasser im Winter in grossen Eist\u00fcrmen gespeichert.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;47a4e8bb-1290-4493-9ff7-76771c89e05e&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/5-2.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/mortalive-3\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;MortAlive&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Inter|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>MortAlive ist ein Projekt mit dem Ziel innovative L\u00f6sungen f\u00fcr das Abdecken von Gletschern mit Schnee zu finden.\u00a0<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/8-1.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/lischana-gletscher\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Lischana Gletscher&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; header_font=&#8220;Inter||||||||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Der Lischana-Gletscher Val Lischana oberhalb von Scuol im Unterengadin hat in den letzten Jahren bereits eine negative Massenbilanz erlitten.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/08\/9-1.png&#8220; url=&#8220;https:\/\/glaciersalive.ch\/nessy-zeroe-schneilanzen\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;NESSy ZeroE Schneilanzen&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Urbanist|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Mit dem schweizerischen patentierten ,,Nessy&#8220;-System\u00a0ist es m\u00f6glich, Schnee ohne elektrische Energie zu erzeugen.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row column_structure=&#8220;1_3,1_3,1_3&#8243; use_custom_gutter=&#8220;on&#8220; gutter_width=&#8220;2&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;47a4e8bb-1290-4493-9ff7-76771c89e05e&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Glacier-experience-1-e1767106616483.png&#8220; title_text=&#8220;Glacier experience&#8220; url=&#8220;https:\/\/glaciersalive.ch\/vr-glacier-experience\/&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;b658643a-0bc7-4423-9eae-fb9a1d80f92c&#8220; filter_saturate=&#8220;100%&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][et_pb_heading title=&#8220;Bernina Glaciers Experience&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;3087ed41-8b08-4192-8134-6e294e4d70ac&#8220; title_font=&#8220;Inter|700|||||||&#8220; custom_margin=&#8220;||0px||false|false&#8220; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_heading][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;65cbe0f9-afc7-4d69-b09a-7a2db0ea44a6&#8243; locked=&#8220;off&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<p>Die neue Ausstellung \u201eStaunen und Verstehen\u201c befindet sich derzeit in Planung und soll im Herbst 2026 er\u00f6ffnet werden.<\/p>\n<h2 style=\"text-align: left;\" data-start=\"81\" data-end=\"139\">\u00a0<\/h2>\n<p style=\"font-weight: 400;\">[\/et_pb_text][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][et_pb_column type=&#8220;1_3&#8243; _builder_version=&#8220;4.25.2&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GlaciersAlive setzt sich mit innovativen und wissenschaftlich begleiteten Projekten f\u00fcr den Schutz von Gletschern ein. Von Ice Stupas \u00fcber reflektierende Schneedecken bis hin zu neuen Beschneiungstechnologien \u2013 die Projekte tragen dazu bei, Schmelzprozesse zu verlangsamen und Wasser langfristig zu sichern.Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"give_campaign_id":0,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-30636","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Projekte | GlaciersAlive<\/title>\n<meta name=\"description\" content=\"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glaciersalive.ch\/en\/projekte-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Projekte | GlaciersAlive\" \/>\n<meta property=\"og:description\" content=\"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glaciersalive.ch\/en\/projekte-2\/\" \/>\n<meta property=\"og:site_name\" content=\"GlaciersAlive\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlaciersAlive\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-27T21:12:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/projekte-2\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/projekte-2\\\/\",\"name\":\"Projekte | GlaciersAlive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\"},\"datePublished\":\"2025-08-31T08:15:26+00:00\",\"dateModified\":\"2026-02-27T21:12:48+00:00\",\"description\":\"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/projekte-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/glaciersalive.ch\\\/projekte-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/projekte-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/glaciersalive.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projekte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"name\":\"GlaciersAlive\",\"description\":\"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glaciersalive.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\",\"name\":\"GlaciersAlive\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"contentUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"width\":1091,\"height\":1031,\"caption\":\"GlaciersAlive\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlaciersAlive\",\"https:\\\/\\\/www.instagram.com\\\/glaciers_alive\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Projekte | GlaciersAlive","description":"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glaciersalive.ch\/en\/projekte-2\/","og_locale":"en_US","og_type":"article","og_title":"Projekte | GlaciersAlive","og_description":"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren","og_url":"https:\/\/glaciersalive.ch\/en\/projekte-2\/","og_site_name":"GlaciersAlive","article_publisher":"https:\/\/www.facebook.com\/GlaciersAlive","article_modified_time":"2026-02-27T21:12:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/glaciersalive.ch\/projekte-2\/","url":"https:\/\/glaciersalive.ch\/projekte-2\/","name":"Projekte | GlaciersAlive","isPartOf":{"@id":"https:\/\/glaciersalive.ch\/#website"},"datePublished":"2025-08-31T08:15:26+00:00","dateModified":"2026-02-27T21:12:48+00:00","description":"Lernen Sie hier unsere einzelnen Projekte kennen und unterst\u00fctzen Sie uns mit einer Spende dabei, die Gletscherwelt lebendig zu bewahren","breadcrumb":{"@id":"https:\/\/glaciersalive.ch\/projekte-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glaciersalive.ch\/projekte-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/glaciersalive.ch\/projekte-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/glaciersalive.ch\/"},{"@type":"ListItem","position":2,"name":"Projekte"}]},{"@type":"WebSite","@id":"https:\/\/glaciersalive.ch\/#website","url":"https:\/\/glaciersalive.ch\/","name":"GlaciersAlive","description":"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.","publisher":{"@id":"https:\/\/glaciersalive.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glaciersalive.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/glaciersalive.ch\/#organization","name":"GlaciersAlive","url":"https:\/\/glaciersalive.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/","url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","contentUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","width":1091,"height":1031,"caption":"GlaciersAlive"},"image":{"@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlaciersAlive","https:\/\/www.instagram.com\/glaciers_alive\/"]}]}},"campaignId":"","_links":{"self":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/pages\/30636","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/comments?post=30636"}],"version-history":[{"count":51,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/pages\/30636\/revisions"}],"predecessor-version":[{"id":32949,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/pages\/30636\/revisions\/32949"}],"wp:attachment":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/media?parent=30636"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}