{"id":30355,"date":"2025-03-10T12:41:25","date_gmt":"2025-03-10T11:41:25","guid":{"rendered":"https:\/\/glaciersalive.ch\/?p=30355"},"modified":"2025-03-10T12:46:51","modified_gmt":"2025-03-10T11:46:51","slug":"ice-stupa-riese-an-der-diavolezza-talstation","status":"publish","type":"post","link":"https:\/\/glaciersalive.ch\/en\/ice-stupa-riese-an-der-diavolezza-talstation\/","title":{"rendered":"Ice Stupa giant at the Diavolezza valley station"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||-33px||false|false&#8220; custom_padding=&#8220;32px||0px||false|false&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;2px||8px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;||-9px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<h4><strong>15 Meter Ice Stupa im Engadin<\/strong><\/h4>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8220;1&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_margin=&#8220;-8px|||||&#8220; custom_padding=&#8220;0px||1px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;0px|||||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.0&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; text_orientation=&#8220;justified&#8220; custom_margin=&#8220;||6px|||&#8220; custom_padding=&#8220;0px||0px|||&#8220; global_colors_info=&#8220;{}&#8220;]<\/p>\n<div class=\"et_pb_module et_pb_text et_pb_text_17  et_pb_text_align_left et_pb_bg_layout_light\">\n<div class=\"et_pb_text_inner\">\n<p>Im Oktober haben wir \u00fcber den Bau des Ice Stupa an der Diavolezza-Talstation berichtet. Im Laufe der Monate ist der Ice Stupa dank der Wetterbedingungen um einiges an Gr\u00f6\u00dfe und Eismasse dazugewonnen und ist nun 15 Meter hoch.<\/p>\n<p>Der Bau eines Ice Stupa an der Diavolezza-Talstation findet seit 2021 jedes Jahr statt. In der Vergangenheit hatten wir immer wieder mit Gefrierproblemen bei den Wasserleitungen zu k\u00e4mpfen. Das Hauptproblem bestand darin, dass eingefrorene Wasserleitungen fast nicht mehr freizubekommen sind. Dank der Weiterentwicklung der Technik konnte das Bew\u00e4sserungssystem verbessert werden. Es wurden kleine Heizungen an den Wasserleitungen angebracht, um sicherzustellen, dass alle wichtigen Stellen vor dem Einschalten eisfrei sind. Seitdem gibt es keine Probleme mehr, und der Ice Stupa kann daher noch gr\u00f6\u00dfer werden.<\/p>\n<\/div>\n<\/div>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_gallery gallery_ids=&#8220;30361,30358,30364,30363,30359,30360,30356,30357&#8243; show_title_and_caption=&#8220;off&#8220; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; title_font_size=&#8220;8px&#8220; caption_font_size=&#8220;10px&#8220; caption_line_height=&#8220;1px&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; sticky_enabled=&#8220;0&#8243;][\/et_pb_gallery][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>15 Meter Ice Stupa im Engadin Im Oktober haben wir \u00fcber den Bau des Ice Stupa an der Diavolezza-Talstation berichtet. Im Laufe der Monate ist der Ice Stupa dank der Wetterbedingungen um einiges an Gr\u00f6\u00dfe und Eismasse dazugewonnen und ist nun 15 Meter hoch. Der Bau eines Ice Stupa an der Diavolezza-Talstation findet seit 2021 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":30359,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,12],"tags":[],"class_list":["post-30355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-ice-stupas"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glaciersalive.ch\/en\/ice-stupa-riese-an-der-diavolezza-talstation\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive\" \/>\n<meta property=\"og:description\" content=\"15 Meter Ice Stupa im Engadin Im Oktober haben wir \u00fcber den Bau des Ice Stupa an der Diavolezza-Talstation berichtet. Im Laufe der Monate ist der Ice Stupa dank der Wetterbedingungen um einiges an Gr\u00f6\u00dfe und Eismasse dazugewonnen und ist nun 15 Meter hoch. Der Bau eines Ice Stupa an der Diavolezza-Talstation findet seit 2021 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glaciersalive.ch\/en\/ice-stupa-riese-an-der-diavolezza-talstation\/\" \/>\n<meta property=\"og:site_name\" content=\"GlaciersAlive\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlaciersAlive\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-10T11:41:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-10T11:46:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin92\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin92\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/\"},\"author\":{\"name\":\"admin92\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/person\\\/67bfc74c749a0eb68ea42d6acd80eda8\"},\"headline\":\"Ice Stupa Riese an der Diavolezza Talstation\",\"datePublished\":\"2025-03-10T11:41:25+00:00\",\"dateModified\":\"2025-03-10T11:46:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/\"},\"wordCount\":361,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ice-4-scaled.jpg\",\"articleSection\":[\"Allgemein\",\"Ice Stupas\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/\",\"name\":\"Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ice-4-scaled.jpg\",\"datePublished\":\"2025-03-10T11:41:25+00:00\",\"dateModified\":\"2025-03-10T11:46:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#primaryimage\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ice-4-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ice-4-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/ice-stupa-riese-an-der-diavolezza-talstation\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/glaciersalive.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ice Stupa Riese an der Diavolezza Talstation\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"name\":\"GlaciersAlive\",\"description\":\"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glaciersalive.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\",\"name\":\"GlaciersAlive\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"contentUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"width\":1091,\"height\":1031,\"caption\":\"GlaciersAlive\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlaciersAlive\",\"https:\\\/\\\/www.instagram.com\\\/glaciers_alive\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/person\\\/67bfc74c749a0eb68ea42d6acd80eda8\",\"name\":\"admin92\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"caption\":\"admin92\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glaciersalive.ch\/en\/ice-stupa-riese-an-der-diavolezza-talstation\/","og_locale":"en_US","og_type":"article","og_title":"Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive","og_description":"15 Meter Ice Stupa im Engadin Im Oktober haben wir \u00fcber den Bau des Ice Stupa an der Diavolezza-Talstation berichtet. Im Laufe der Monate ist der Ice Stupa dank der Wetterbedingungen um einiges an Gr\u00f6\u00dfe und Eismasse dazugewonnen und ist nun 15 Meter hoch. Der Bau eines Ice Stupa an der Diavolezza-Talstation findet seit 2021 [&hellip;]","og_url":"https:\/\/glaciersalive.ch\/en\/ice-stupa-riese-an-der-diavolezza-talstation\/","og_site_name":"GlaciersAlive","article_publisher":"https:\/\/www.facebook.com\/GlaciersAlive","article_published_time":"2025-03-10T11:41:25+00:00","article_modified_time":"2025-03-10T11:46:51+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg","type":"image\/jpeg"}],"author":"admin92","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin92","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#article","isPartOf":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/"},"author":{"name":"admin92","@id":"https:\/\/glaciersalive.ch\/#\/schema\/person\/67bfc74c749a0eb68ea42d6acd80eda8"},"headline":"Ice Stupa Riese an der Diavolezza Talstation","datePublished":"2025-03-10T11:41:25+00:00","dateModified":"2025-03-10T11:46:51+00:00","mainEntityOfPage":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/"},"wordCount":361,"commentCount":0,"publisher":{"@id":"https:\/\/glaciersalive.ch\/#organization"},"image":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#primaryimage"},"thumbnailUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg","articleSection":["Allgemein","Ice Stupas"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/","url":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/","name":"Ice Stupa Riese an der Diavolezza Talstation | GlaciersAlive","isPartOf":{"@id":"https:\/\/glaciersalive.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#primaryimage"},"image":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#primaryimage"},"thumbnailUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg","datePublished":"2025-03-10T11:41:25+00:00","dateModified":"2025-03-10T11:46:51+00:00","breadcrumb":{"@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#primaryimage","url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg","contentUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/03\/ice-4-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/glaciersalive.ch\/ice-stupa-riese-an-der-diavolezza-talstation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/glaciersalive.ch\/"},{"@type":"ListItem","position":2,"name":"Ice Stupa Riese an der Diavolezza Talstation"}]},{"@type":"WebSite","@id":"https:\/\/glaciersalive.ch\/#website","url":"https:\/\/glaciersalive.ch\/","name":"GlaciersAlive","description":"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.","publisher":{"@id":"https:\/\/glaciersalive.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glaciersalive.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/glaciersalive.ch\/#organization","name":"GlaciersAlive","url":"https:\/\/glaciersalive.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/","url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","contentUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","width":1091,"height":1031,"caption":"GlaciersAlive"},"image":{"@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlaciersAlive","https:\/\/www.instagram.com\/glaciers_alive\/"]},{"@type":"Person","@id":"https:\/\/glaciersalive.ch\/#\/schema\/person\/67bfc74c749a0eb68ea42d6acd80eda8","name":"admin92","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","caption":"admin92"}}]}},"_links":{"self":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/30355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/comments?post=30355"}],"version-history":[{"count":3,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/30355\/revisions"}],"predecessor-version":[{"id":30369,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/30355\/revisions\/30369"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/media\/30359"}],"wp:attachment":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/media?parent=30355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/categories?post=30355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/tags?post=30355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}