{"id":32248,"date":"2025-12-07T17:03:34","date_gmt":"2025-12-07T16:03:34","guid":{"rendered":"https:\/\/glaciersalive.ch\/?p=32248"},"modified":"2026-01-07T08:38:01","modified_gmt":"2026-01-07T07:38:01","slug":"nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming","status":"publish","type":"post","link":"https:\/\/glaciersalive.ch\/en\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/","title":{"rendered":"Sustainable snow and ice protection: New organic fleece for glaciers and snow farming"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8220;1&#8243; admin_label=&#8220;section&#8220; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;5px||1px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||5px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;on|off|off&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4 id=\"m_-617721019121550601isPasted\"><strong>Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming<\/strong><\/h4>\n<p>Der Verlust von Gletschern und Schneefl\u00e4chen schreitet weltweit voran. F\u00fcr \u00fcber 200 Millionen Menschen ist dies von existenzieller Bedeutung, weshalb es effektive und umweltvertr\u00e4gliche L\u00f6sungen braucht mit lokaler Wirkung. GlaciersAlive hat hierf\u00fcr verschiedene Materialien ohne Mikroplastik zur Abdeckung von Gletschern getestet und ausgewertet \u2013 mit einem klaren Ergebnis:<br \/>Mit dem vollst\u00e4ndig biologisch abbaubaren Vlies <a href=\"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/SCHOELLKOPF-SNOW-Protect_D_06.25.pdf\">SCHOELLKOPF SNOW Protect<\/a> der Firma SCHOELLKOPF steht ein Material aus Westeuropa zur Verf\u00fcgung, das in den unabh\u00e4ngigen Feldstudien \u00fcberzeugte und Snowfarming sowie Gletscherschutz nachhaltig unterst\u00fctzt.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;||5px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;off|on|on&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4 id=\"m_-617721019121550601isPasted\" style=\"text-align: left;\"><strong>Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming<\/strong><\/h4>\n<p style=\"text-align: left;\">Der Verlust von Gletschern und Schneefl\u00e4chen schreitet weltweit voran. F\u00fcr \u00fcber 200 Millionen Menschen ist dies von existenzieller Bedeutung, weshalb es effektive und umweltvertr\u00e4gliche L\u00f6sungen braucht mit lokaler Wirkung. GlaciersAlive hat hierf\u00fcr verschiedene Materialien ohne Mikroplastik zur Abdeckung von Gletschern getestet und ausgewertet \u2013 mit einem klaren Ergebnis:<br \/>Mit dem vollst\u00e4ndig biologisch abbaubaren Vlies <a href=\"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/SCHOELLKOPF-SNOW-Protect_D_06.25.pdf\">SCHOELLKOPF SNOW Protect<\/a> der Firma SCHOELLKOPF steht ein Material aus Westeuropa zur Verf\u00fcgung, das in den unabh\u00e4ngigen Feldstudien \u00fcberzeugte und Snowfarming sowie Gletscherschutz nachhaltig unterst\u00fctzt.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;13px||6px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; custom_margin=&#8220;||-1px|||&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;on|off|off&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4 id=\"m_-617721019121550601isPasted\"><strong style=\"font-size: 16px; color: #000000;\">Warum ein Bio-Vlies?<\/strong><\/h4>\n<p>Konventionelle PP-Vliese (Polypropylen-Vliese) verursachen Mikroplastik, ein Problem f\u00fcr Natur und Umwelt. Deshalb haben wir 2022 auf der Diavolezza mit Unterst\u00fctzung von<a href=\"https:\/\/www.mastercard.com\/ch\/de\/for-the-world\/corporate-impact.html\"> Mastercard<\/a> auf der Diavolezza verschiedene Alternativen getestet. Das Ergebnis: Nur das neu entwickelte PLA-Vlies (Polylactide\/Ploymilchs\u00e4ure) von SCHOELLKOPF bietet aktuell dieselbe Schutzwirkung wie PP-Vliese, jedoch ohne Umweltbelastung durch Mikroplastik.<\/p>\n<p><strong>Erprobte Leistung in Feldstudien<\/strong><\/p>\n<p>2024 und 2025 wurden die Vliese an verschiedenen Standorten in der Schweiz intensiv getestet, u. a. auf Corvatsch, Diavolezza, Titlis, Zermatt und Laax. Die Resultate zeigen eine gleichwertige Schutzwirkung im Vergleich zu PP-Vlies, bei deutlich besserer Umweltbilanz. Die Optimierung des PLA-Vlies hinsichtlich Zugfestigkeit, st\u00e4rkerer Lichtreflexion und schmutzabweisender Oberfl\u00e4che l\u00e4uft weiter.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row admin_label=&#8220;row&#8220; _builder_version=&#8220;4.16&#8243; background_size=&#8220;initial&#8220; background_position=&#8220;top_left&#8220; background_repeat=&#8220;repeat&#8220; custom_padding=&#8220;13px||6px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.16&#8243; custom_padding=&#8220;|||&#8220; global_colors_info=&#8220;{}&#8220; custom_padding__hover=&#8220;|||&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; custom_margin=&#8220;||-1px|||&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;off|on|on&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<h4 id=\"m_-617721019121550601isPasted\" style=\"text-align: left;\"><strong style=\"font-size: 16px; color: #000000;\">Warum ein Bio-Vlies?<\/strong><\/h4>\n<p style=\"text-align: left;\">Konventionelle PP-Vliese (Polypropylen-Vliese) verursachen Mikroplastik, ein Problem f\u00fcr Natur und Umwelt. Deshalb haben wir 2022 auf der Diavolezza mit Unterst\u00fctzung von<a href=\"https:\/\/www.mastercard.com\/ch\/de\/for-the-world\/corporate-impact.html\"> Mastercard<\/a> auf der Diavolezza verschiedene Alternativen getestet. Das Ergebnis: Nur das neu entwickelte PLA-Vlies (Polylactide\/Ploymilchs\u00e4ure) von SCHOELLKOPF bietet aktuell dieselbe Schutzwirkung wie PP-Vliese, jedoch ohne Umweltbelastung durch Mikroplastik.<\/p>\n<p style=\"text-align: left;\"><strong>Erprobte Leistung in Feldstudien<\/strong><\/p>\n<p style=\"text-align: left;\">2024 und 2025 wurden die Vliese an verschiedenen Standorten in der Schweiz intensiv getestet, u. a. auf Corvatsch, Diavolezza, Titlis, Zermatt und Laax. Die Resultate zeigen eine gleichwertige Schutzwirkung im Vergleich zu PP-Vlies, bei deutlich besserer Umweltbilanz. Die Optimierung des PLA-Vlies hinsichtlich Zugfestigkeit, st\u00e4rkerer Lichtreflexion und schmutzabweisender Oberfl\u00e4che l\u00e4uft weiter.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;10px||5px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.4&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;on|off|off&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p><strong>Fazit<\/strong><\/p>\n<p>Mit dem biologisch abbaubaren SNOW Protect Bio-Vlies wird Gletscherschutz effizienter, \u00f6kologischer und zukunftsf\u00e4higer. Es vereint wissenschaftliche Erkenntnisse, nachhaltige Materialien und praktische Anwendung \u2013 ein wichtiger Schritt, um alpine Landschaften langfristig zu sch\u00fctzen und kommende Generationen f\u00fcr ihre Bedeutung zu sensibilisieren.<\/p>\n<p>[\/et_pb_text][et_pb_text _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; text_font_size=&#8220;16px&#8220; text_orientation=&#8220;justified&#8220; hover_enabled=&#8220;0&#8243; global_colors_info=&#8220;{}&#8220; disabled_on=&#8220;off|on|on&#8220; sticky_enabled=&#8220;0&#8243;]<\/p>\n<p style=\"text-align: left;\"><strong>Fazit<\/strong><\/p>\n<p style=\"text-align: left;\">Mit dem biologisch abbaubaren SNOW Protect Bio-Vlies wird Gletscherschutz effizienter, \u00f6kologischer und zukunftsf\u00e4higer. Es vereint wissenschaftliche Erkenntnisse, nachhaltige Materialien und praktische Anwendung \u2013 ein wichtiger Schritt, um alpine Landschaften langfristig zu sch\u00fctzen und kommende Generationen f\u00fcr ihre Bedeutung zu sensibilisieren.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Laaxvlies.png&#8220; title_text=&#8220;Laaxvlies&#8220; align=&#8220;center&#8220; disabled_on=&#8220;on|off|off&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; module_alignment=&#8220;center&#8220; height=&#8220;472px&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; custom_padding=&#8220;1px||1px|||&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_column type=&#8220;4_4&#8243; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][et_pb_image src=&#8220;https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Laaxvlies.png&#8220; title_text=&#8220;Laaxvlies&#8220; disabled_on=&#8220;off|on|on&#8220; _builder_version=&#8220;4.27.5&#8243; _module_preset=&#8220;default&#8220; global_colors_info=&#8220;{}&#8220;][\/et_pb_image][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming Der Verlust von Gletschern und Schneefl\u00e4chen schreitet weltweit voran. F\u00fcr \u00fcber 200 Millionen Menschen ist dies von existenzieller Bedeutung, weshalb es effektive und umweltvertr\u00e4gliche L\u00f6sungen braucht mit lokaler Wirkung. GlaciersAlive hat hierf\u00fcr verschiedene Materialien ohne Mikroplastik zur Abdeckung von Gletschern getestet und ausgewertet \u2013 mit [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":32251,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1,10],"tags":[],"class_list":["post-32248","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-allgemein","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming | GlaciersAlive<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/glaciersalive.ch\/en\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming | GlaciersAlive\" \/>\n<meta property=\"og:description\" content=\"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming Der Verlust von Gletschern und Schneefl\u00e4chen schreitet weltweit voran. F\u00fcr \u00fcber 200 Millionen Menschen ist dies von existenzieller Bedeutung, weshalb es effektive und umweltvertr\u00e4gliche L\u00f6sungen braucht mit lokaler Wirkung. GlaciersAlive hat hierf\u00fcr verschiedene Materialien ohne Mikroplastik zur Abdeckung von Gletschern getestet und ausgewertet \u2013 mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/glaciersalive.ch\/en\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/\" \/>\n<meta property=\"og:site_name\" content=\"GlaciersAlive\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/GlaciersAlive\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-07T16:03:34+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-07T07:38:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin92\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin92\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/\"},\"author\":{\"name\":\"admin92\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/person\\\/67bfc74c749a0eb68ea42d6acd80eda8\"},\"headline\":\"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &#038; Snowfarming\",\"datePublished\":\"2025-12-07T16:03:34+00:00\",\"dateModified\":\"2026-01-07T07:38:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/\"},\"wordCount\":1034,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Biovlies-scaled.jpg\",\"articleSection\":[\"Allgemein\",\"News\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/\",\"name\":\"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher & Snowfarming | GlaciersAlive\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Biovlies-scaled.jpg\",\"datePublished\":\"2025-12-07T16:03:34+00:00\",\"dateModified\":\"2026-01-07T07:38:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#primaryimage\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Biovlies-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Biovlies-scaled.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/glaciersalive.ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &#038; Snowfarming\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#website\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"name\":\"GlaciersAlive\",\"description\":\"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.\",\"publisher\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/glaciersalive.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#organization\",\"name\":\"GlaciersAlive\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"contentUrl\":\"https:\\\/\\\/glaciersalive.ch\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/GlaciersAlivelogo.jpg\",\"width\":1091,\"height\":1031,\"caption\":\"GlaciersAlive\"},\"image\":{\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/GlaciersAlive\",\"https:\\\/\\\/www.instagram.com\\\/glaciers_alive\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/glaciersalive.ch\\\/#\\\/schema\\\/person\\\/67bfc74c749a0eb68ea42d6acd80eda8\",\"name\":\"admin92\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g\",\"caption\":\"admin92\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher & Snowfarming | GlaciersAlive","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/glaciersalive.ch\/en\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/","og_locale":"en_US","og_type":"article","og_title":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher & Snowfarming | GlaciersAlive","og_description":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &amp; Snowfarming Der Verlust von Gletschern und Schneefl\u00e4chen schreitet weltweit voran. F\u00fcr \u00fcber 200 Millionen Menschen ist dies von existenzieller Bedeutung, weshalb es effektive und umweltvertr\u00e4gliche L\u00f6sungen braucht mit lokaler Wirkung. GlaciersAlive hat hierf\u00fcr verschiedene Materialien ohne Mikroplastik zur Abdeckung von Gletschern getestet und ausgewertet \u2013 mit [&hellip;]","og_url":"https:\/\/glaciersalive.ch\/en\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/","og_site_name":"GlaciersAlive","article_publisher":"https:\/\/www.facebook.com\/GlaciersAlive","article_published_time":"2025-12-07T16:03:34+00:00","article_modified_time":"2026-01-07T07:38:01+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg","type":"image\/jpeg"}],"author":"admin92","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin92","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#article","isPartOf":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/"},"author":{"name":"admin92","@id":"https:\/\/glaciersalive.ch\/#\/schema\/person\/67bfc74c749a0eb68ea42d6acd80eda8"},"headline":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &#038; Snowfarming","datePublished":"2025-12-07T16:03:34+00:00","dateModified":"2026-01-07T07:38:01+00:00","mainEntityOfPage":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/"},"wordCount":1034,"commentCount":0,"publisher":{"@id":"https:\/\/glaciersalive.ch\/#organization"},"image":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#primaryimage"},"thumbnailUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg","articleSection":["Allgemein","News"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/","url":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/","name":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher & Snowfarming | GlaciersAlive","isPartOf":{"@id":"https:\/\/glaciersalive.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#primaryimage"},"image":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#primaryimage"},"thumbnailUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg","datePublished":"2025-12-07T16:03:34+00:00","dateModified":"2026-01-07T07:38:01+00:00","breadcrumb":{"@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#primaryimage","url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg","contentUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/Biovlies-scaled.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/glaciersalive.ch\/nachhaltiger-schnee-und-eisschutz-neues-bio-vlies-fuer-gletscher-snowfarming\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/glaciersalive.ch\/"},{"@type":"ListItem","position":2,"name":"Nachhaltiger Schnee- und Eisschutz: Neues Bio-Vlies f\u00fcr Gletscher &#038; Snowfarming"}]},{"@type":"WebSite","@id":"https:\/\/glaciersalive.ch\/#website","url":"https:\/\/glaciersalive.ch\/","name":"GlaciersAlive","description":"Gletscherpflege f\u00fcr die nachhaltigen Sicherung der Wasserversorgung in Gebirgsregionen.","publisher":{"@id":"https:\/\/glaciersalive.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/glaciersalive.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/glaciersalive.ch\/#organization","name":"GlaciersAlive","url":"https:\/\/glaciersalive.ch\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/","url":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","contentUrl":"https:\/\/glaciersalive.ch\/wp-content\/uploads\/2025\/12\/GlaciersAlivelogo.jpg","width":1091,"height":1031,"caption":"GlaciersAlive"},"image":{"@id":"https:\/\/glaciersalive.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/GlaciersAlive","https:\/\/www.instagram.com\/glaciers_alive\/"]},{"@type":"Person","@id":"https:\/\/glaciersalive.ch\/#\/schema\/person\/67bfc74c749a0eb68ea42d6acd80eda8","name":"admin92","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6c38a62567b570122238e649c273e5721746425e53355e63a336da597a985a3f?s=96&d=mm&r=g","caption":"admin92"}}]}},"_links":{"self":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/32248","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/comments?post=32248"}],"version-history":[{"count":12,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/32248\/revisions"}],"predecessor-version":[{"id":32840,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/posts\/32248\/revisions\/32840"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/media\/32251"}],"wp:attachment":[{"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/media?parent=32248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/categories?post=32248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/glaciersalive.ch\/en\/wp-json\/wp\/v2\/tags?post=32248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}